{"id":2381,"date":"2016-07-27T04:59:03","date_gmt":"2016-07-26T21:59:03","guid":{"rendered":"https:\/\/www.emoi-france.fr\/product\/boucle-doreille-recyclee-goutte-de-lumiere\/"},"modified":"2017-05-23T01:56:19","modified_gmt":"2017-05-22T18:56:19","slug":"boucle-doreille-recyclee-goutte-de-lumiere","status":"publish","type":"product","link":"https:\/\/www.emoi-france.fr\/fr\/produit\/boucle-doreille-recyclee-goutte-de-lumiere\/","title":{"rendered":"Boucle d&rsquo;oreille \u00ab\u00a0Goutte de lumi\u00e8re\u00a0\u00bb"},"content":{"rendered":"<p>\u00ab\u00a0Boucle d&rsquo;oreille recycl\u00e9e avec des petits triangles suspendues sur une chaine.<\/p>\n<p>Collection\u00a0\u00bb goute de lumiere \u00ab\u00a0, r\u00e9alis\u00e9\u00a0\u00e0 partir d&#8217;emballages de jus de fruits.<br \/>\nMotif multicolore.<br \/>\nLe longueur total de boucle d&rsquo;oreille\u00a0est environ 5 cm.<br \/>\nCollection de bijoux recycl\u00e9s, cr\u00e9e par E-MOI.<br \/>\nProduits issues du commerce \u00e9quitable,\u00a0fabriqu\u00e9s par notre partenaire coop\u00e9ratif des femmes aux Philippines \u00ab\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boucle d&rsquo;oreille recycl\u00e9e avec des petites triangles suspendues sur une chaine. Collection \u00abgoutte de lumiere\u00bb, r\u00e9alis\u00e9 \u00e0 partir d&#8217;emballages de jus de fruits.<\/p>\n","protected":false},"featured_media":2583,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[161,211,212,222,264,247,231,195,221],"product_tag":[],"class_list":["post-2381","product","type-product","status-publish","has-post-thumbnail","product_cat-bijoux-recycles-fr","product_cat-boucle-doreille-recyclee","product_cat-boucles-doreilles-recycle-en-emballages-de-jus-fruits","product_cat-collier-recycle-en-emballages-de-jus-de-fruits","product_cat-emballage-de-jus-de-fruits","product_cat-goutte-de-lumiere","product_cat-par-collection","product_cat-par-fonction","product_cat-par-matiere-fr","first","instock","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Boucle d&#039;oreille &quot;Goutte de lumi\u00e8re&quot; - E-Moi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emoi-france.fr\/fr\/produit\/boucle-doreille-recyclee-goutte-de-lumiere\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boucle d&#039;oreille &quot;Goutte de lumi\u00e8re&quot; - E-Moi\" \/>\n<meta property=\"og:description\" content=\"Boucle d&#039;oreille recycl\u00e9e avec des petites triangles suspendues sur une chaine. Collection \u00abgoutte de lumiere\u00bb, r\u00e9alis\u00e9 \u00e0 partir d&#039;emballages de jus de fruits.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emoi-france.fr\/fr\/produit\/boucle-doreille-recyclee-goutte-de-lumiere\/\" \/>\n<meta property=\"og:site_name\" content=\"E-Moi\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-22T18:56:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emoi-france.fr\/wp-content\/uploads\/2016\/07\/recycled-earing-lightdrop.png\" \/>\n\t<meta property=\"og:image:width\" content=\"371\" \/>\n\t<meta property=\"og:image:height\" content=\"392\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emoi-france.fr\\\/fr\\\/produit\\\/boucle-doreille-recyclee-goutte-de-lumiere\\\/\",\"url\":\"https:\\\/\\\/www.emoi-france.fr\\\/fr\\\/produit\\\/boucle-doreille-recyclee-goutte-de-lumiere\\\/\",\"name\":\"Boucle d'oreille \\\"Goutte de lumi\u00e8re\\\" - E-Moi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emoi-france.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emoi-france.fr\\\/fr\\\/produit\\\/boucle-doreille-recyclee-goutte-de-lumiere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emoi-france.fr\\\/fr\\\/produit\\\/boucle-doreille-recyclee-goutte-de-lumiere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emoi-france.fr\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/recycled-earing-lightdrop.png\",\"datePublished\":\"2016-07-26T21:59:03+00:00\",\"dateModified\":\"2017-05-22T18:56:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emoi-france.fr\\\/fr\\\/produit\\\/boucle-doreille-recyclee-goutte-de-lumiere\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emoi-france.fr\\\/fr\\\/produit\\\/boucle-doreille-recyclee-goutte-de-lumiere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.emoi-france.fr\\\/fr\\\/produit\\\/boucle-doreille-recyclee-goutte-de-lumiere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emoi-france.fr\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/recycled-earing-lightdrop.png\",\"contentUrl\":\"https:\\\/\\\/www.emoi-france.fr\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/recycled-earing-lightdrop.png\",\"width\":371,\"height\":392,\"caption\":\"boucle-d'oreille-recycl\u00e9-goutte de lumiere\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emoi-france.fr\\\/fr\\\/produit\\\/boucle-doreille-recyclee-goutte-de-lumiere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.emoi-france.fr\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique en ligne\",\"item\":\"https:\\\/\\\/www.emoi-france.fr\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Boucle d&rsquo;oreille \u00ab\u00a0Goutte de lumi\u00e8re\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emoi-france.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.emoi-france.fr\\\/\",\"name\":\"E-Moi\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emoi-france.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boucle d'oreille \"Goutte de lumi\u00e8re\" - E-Moi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emoi-france.fr\/fr\/produit\/boucle-doreille-recyclee-goutte-de-lumiere\/","og_locale":"fr_FR","og_type":"article","og_title":"Boucle d'oreille \"Goutte de lumi\u00e8re\" - E-Moi","og_description":"Boucle d'oreille recycl\u00e9e avec des petites triangles suspendues sur une chaine. Collection \u00abgoutte de lumiere\u00bb, r\u00e9alis\u00e9 \u00e0 partir d'emballages de jus de fruits.","og_url":"https:\/\/www.emoi-france.fr\/fr\/produit\/boucle-doreille-recyclee-goutte-de-lumiere\/","og_site_name":"E-Moi","article_modified_time":"2017-05-22T18:56:19+00:00","og_image":[{"width":371,"height":392,"url":"https:\/\/www.emoi-france.fr\/wp-content\/uploads\/2016\/07\/recycled-earing-lightdrop.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.emoi-france.fr\/fr\/produit\/boucle-doreille-recyclee-goutte-de-lumiere\/","url":"https:\/\/www.emoi-france.fr\/fr\/produit\/boucle-doreille-recyclee-goutte-de-lumiere\/","name":"Boucle d'oreille \"Goutte de lumi\u00e8re\" - E-Moi","isPartOf":{"@id":"https:\/\/www.emoi-france.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emoi-france.fr\/fr\/produit\/boucle-doreille-recyclee-goutte-de-lumiere\/#primaryimage"},"image":{"@id":"https:\/\/www.emoi-france.fr\/fr\/produit\/boucle-doreille-recyclee-goutte-de-lumiere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emoi-france.fr\/wp-content\/uploads\/2016\/07\/recycled-earing-lightdrop.png","datePublished":"2016-07-26T21:59:03+00:00","dateModified":"2017-05-22T18:56:19+00:00","breadcrumb":{"@id":"https:\/\/www.emoi-france.fr\/fr\/produit\/boucle-doreille-recyclee-goutte-de-lumiere\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emoi-france.fr\/fr\/produit\/boucle-doreille-recyclee-goutte-de-lumiere\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.emoi-france.fr\/fr\/produit\/boucle-doreille-recyclee-goutte-de-lumiere\/#primaryimage","url":"https:\/\/www.emoi-france.fr\/wp-content\/uploads\/2016\/07\/recycled-earing-lightdrop.png","contentUrl":"https:\/\/www.emoi-france.fr\/wp-content\/uploads\/2016\/07\/recycled-earing-lightdrop.png","width":371,"height":392,"caption":"boucle-d'oreille-recycl\u00e9-goutte de lumiere"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emoi-france.fr\/fr\/produit\/boucle-doreille-recyclee-goutte-de-lumiere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.emoi-france.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique en ligne","item":"https:\/\/www.emoi-france.fr\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Boucle d&rsquo;oreille \u00ab\u00a0Goutte de lumi\u00e8re\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.emoi-france.fr\/#website","url":"https:\/\/www.emoi-france.fr\/","name":"E-Moi","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emoi-france.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.emoi-france.fr\/fr\/wp-json\/wp\/v2\/product\/2381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emoi-france.fr\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.emoi-france.fr\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emoi-france.fr\/fr\/wp-json\/wp\/v2\/comments?post=2381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emoi-france.fr\/fr\/wp-json\/wp\/v2\/media\/2583"}],"wp:attachment":[{"href":"https:\/\/www.emoi-france.fr\/fr\/wp-json\/wp\/v2\/media?parent=2381"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.emoi-france.fr\/fr\/wp-json\/wp\/v2\/product_brand?post=2381"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.emoi-france.fr\/fr\/wp-json\/wp\/v2\/product_cat?post=2381"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.emoi-france.fr\/fr\/wp-json\/wp\/v2\/product_tag?post=2381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}